{"id":307,"date":"2021-05-10T07:45:00","date_gmt":"2021-05-10T05:45:00","guid":{"rendered":"https:\/\/france-cadastre.fr\/site\/?p=307"},"modified":"2024-11-25T10:19:28","modified_gmt":"2024-11-25T09:19:28","slug":"plus-value-terrain-2021","status":"publish","type":"post","link":"https:\/\/france-cadastre.fr\/site\/plus-value-terrain-2021\/","title":{"rendered":"PLUS-VALUE TERRAIN 2021"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large is-style-rounded\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/france-cadastre.fr\/site\/wp-content\/uploads\/2021\/05\/plus-value-france-casdastre.jpg\" alt=\"\" class=\"wp-image-308\" \/><\/figure>\n\n\n\n<p>En ce qui concerne la taxation des plus-values \u200b\u200br\u00e9alis\u00e9es lors de la vente du terrain, les contribuables se trouveront confront\u00e9s \u00e0 plusieurs situations, selon que le terrain en question est h\u00e9rit\u00e9, qu&rsquo;il s&rsquo;agisse d&rsquo;une exploitation agricole, ou qu&rsquo;il soit possible ou impossible \u00e0 construire.<\/p>\n\n\n\n<p>Lorsqu&rsquo;un propri\u00e9taire foncier qui poss\u00e8de un terrain sur lequel un b\u00e2timent peut \u00eatre construit d\u00e9cide de le vendre, des gains en capital sur le terrain \u00e0 construire se produiront. Une fois cette \u00e9tape franchie, le vendeur per\u00e7oit une plus-value lors de la vente de son bien \u00e0 un prix sup\u00e9rieur \u00e0 son prix d&rsquo;achat. Tout au long de son cycle de vie, la valeur d\u2019un terrain peut augmenter, et c\u2019est cette \u00e9volution qui justifie la demande du c\u00e9dant de prix plus \u00e9lev\u00e9s.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>CALCUL\u00a0: la plus-value sur un terrain.<\/li><\/ul>\n\n\n\n<p>Par cons\u00e9quent, le calcul des plus-values \u200b\u200bfonci\u00e8res \u00e9quivaut \u00e0 soustraire le prix d&rsquo;achat du terrain du prix de vente. Lorsque ce dernier est sup\u00e9rieur au prix convenu au moment de l&rsquo;acquisition, il s&rsquo;agit d&rsquo;un nombre positif, ce que nous appelons des plus-values. \u00c0 l&rsquo;inverse, si le prix de vente est inf\u00e9rieur au prix d&rsquo;achat initial, on parle alors de perte en capital, ce qui signifie que le propri\u00e9taire qui a renonc\u00e9 au risque subirait une perte s&rsquo;il vendait ce prix \u00e0 ce prix.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>TAXATION\u00a0: la plus-value sur un terrain<\/li><\/ul>\n\n\n\n<p>La r\u00e9duction de l&rsquo;imp\u00f4t sur les plus-values \u200b\u200br\u00e9alis\u00e9 dans le cadre du processus de vente de terrains \u00e0 b\u00e2tir est un moyen exploit\u00e9 par le gouvernement pour limiter la r\u00e9tention des terrains et des terrains \u00e0 b\u00e2tir afin de promouvoir la construction de logements et ainsi freiner la hausse des prix de l&rsquo;immobilier. Ainsi, depuis le 1er septembre 2014, les plus-values \u200b\u200bde cession de terrains \u00e0 b\u00e2tir seront exon\u00e9r\u00e9es de l&rsquo;imp\u00f4t sur le revenu et ramen\u00e9es \u00e0 22 ans, et le gouvernement veut encourager les possesseurs de terrains constructibles \u00e0 s&rsquo;en s\u00e9parer. Veuillez noter que la d\u00e9duction pour gains en capital pour les cotisations de s\u00e9curit\u00e9 sociale ne sera disponible qu&rsquo;apr\u00e8s 30 ans.<\/p>\n\n\n\n<p>De plus, \u00e0 compter du 1er janvier 2018, si les deux conditions suivantes sont remplies, les plus-values \u200b\u200bprovenant de la vente de terrains \u00e0 b\u00e2tir situ\u00e9s en Zone A et A bis pourront \u00eatre r\u00e9duites de 70% ou 85% notamment :<\/p>\n\n\n\n<p>Pr\u00e9alablement \u00e0 la vente, un engagement de vente unilat\u00e9ral (ou alliance) a \u00e9t\u00e9 sign\u00e9 et obtenu \u00e0 une date comprise entre le 1er janvier 2018 et le 31 d\u00e9cembre 2020.<\/p>\n\n\n\n<p>La vente doit \u00eatre effectu\u00e9e au plus tard le 31 d\u00e9cembre de la deuxi\u00e8me ann\u00e9e qui la suit au cours de laquelle une certaine date a \u00e9t\u00e9 promise. Ainsi, en pratique, l&rsquo;allocation sp\u00e9ciale peut donc \u00eatre appliqu\u00e9e aux traitements effectu\u00e9s avant le 31 d\u00e9cembre 2022.<\/p>\n\n\n\n<p>Pour que le c\u00e9dant b\u00e9n\u00e9ficie de cette exon\u00e9ration, le vendeur doit \u00e9galement s&rsquo;engager \u00e0 construire une maison sur le terrain vendu dans un d\u00e9lai de quatre ans \u00e0 compter de la date d&rsquo;achat. Sa promesse doit figurer dans l&rsquo;acte de vente.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Plus-value\u00a0: terrain non constructible.<\/li><\/ul>\n\n\n\n<p>La vente de terrains non constructibles ne conf\u00e8re pas de droits relatifs \u00e0 des \u00e9quipements sp\u00e9cifiques, ce qui implique des plus-values \u200b\u200ben d\u00e9coulant. En revanche, si une parcelle de terrain peut \u00eatre construite apr\u00e8s r\u00e9vision du plan local de la ville, le taux d&rsquo;imposition des plus-values \u200b\u200bsur la vente sera compris entre 5% et 10%, en fonction de son importance pour l&rsquo;acquisition du prix.<\/p>\n\n\n\n<p>Sauf si le terrain est vendu \u00e0 un prix inf\u00e9rieur \u00e0 15000 euros, si la plus-value est inf\u00e9rieure \u00e0 10 fois le prix d&rsquo;achat, ou si le terrain est rendu constructible avant le 13 janvier 2010, ou si la vente est due \u00e0 l&rsquo;acquisition d&rsquo;un terrain, de la d\u00e9claration d&rsquo;utilit\u00e9 publique \u00ab&nbsp;expropriation&nbsp;\u00bb. Dans ces circonstances, le c\u00e9dant peut b\u00e9n\u00e9ficier d&rsquo;une exon\u00e9ration fiscale.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Plus-value\u00a0: terrain agricole.<\/li><\/ul>\n\n\n\n<p>L\u2019imposition des plus-values \u200b\u200bde cession de terres agricoles d\u00e9pend de sa position dans la succession du contribuable. \u00c9videmment, par exemple, si les terres agricoles font partie du bilan professionnel d&rsquo;un agriculteur ou d&rsquo;un agriculteur, tout imp\u00f4t est exon\u00e9r\u00e9. En revanche, si le bien fait partie d&rsquo;un domaine priv\u00e9, il doit \u00eatre soumis au syst\u00e8me d&rsquo;imposition de droit commun sur la cession des plus-values.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Plus-value\u00a0: terrain re\u00e7u en h\u00e9ritage.<\/li><\/ul>\n\n\n\n<p>Lors de la cession d&rsquo;un terrain librement acquis, par exemple dans le cadre d&rsquo;un h\u00e9ritage, il est important de s&rsquo;assurer que la valeur marchande du bien est correctement ajust\u00e9e. En fait, il doit inclure les co\u00fbts li\u00e9s aux successions, qu&rsquo;il y ait des droits de succession, des frais d&rsquo;enregistrement ou de notarisation. En augmentant ainsi la valeur marchande du terrain acquis en h\u00e9ritage, si le c\u00e9dant veut maximiser les plus-values \u200b\u200bde cession, il devra \u00e9galement augmenter le prix.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En ce qui concerne la taxation des plus-values \u200b\u200br\u00e9alis\u00e9es lors de la vente du terrain, les contribuables se trouveront confront\u00e9s \u00e0 plusieurs situations, selon que le terrain en question est h\u00e9rit\u00e9, qu&rsquo;il s&rsquo;agisse d&rsquo;une exploitation agricole, ou qu&rsquo;il soit possible&hellip;<\/p>\n","protected":false},"author":1,"featured_media":308,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"post_series":[],"class_list":["post-307","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ressources","entry","has-media"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>PLUS-VALUE TERRAIN 2021 - France Cadastre<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/france-cadastre.fr\/site\/plus-value-terrain-2021\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PLUS-VALUE TERRAIN 2021 - France Cadastre\" \/>\n<meta property=\"og:description\" content=\"En ce qui concerne la taxation des plus-values \u200b\u200br\u00e9alis\u00e9es lors de la vente du terrain, les contribuables se trouveront confront\u00e9s \u00e0 plusieurs situations, selon que le terrain en question est h\u00e9rit\u00e9, qu&rsquo;il s&rsquo;agisse d&rsquo;une exploitation agricole, ou qu&rsquo;il soit possible&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/france-cadastre.fr\/site\/plus-value-terrain-2021\/\" \/>\n<meta property=\"og:site_name\" content=\"France Cadastre\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-10T05:45:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-25T09:19:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/france-cadastre.fr\/site\/wp-content\/uploads\/2021\/05\/plus-value-france-casdastre.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"valentin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"valentin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/france-cadastre.fr\/site\/plus-value-terrain-2021\/\",\"url\":\"https:\/\/france-cadastre.fr\/site\/plus-value-terrain-2021\/\",\"name\":\"PLUS-VALUE TERRAIN 2021 - France Cadastre\",\"isPartOf\":{\"@id\":\"https:\/\/france-cadastre.fr\/site\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/france-cadastre.fr\/site\/plus-value-terrain-2021\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/france-cadastre.fr\/site\/plus-value-terrain-2021\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/france-cadastre.fr\/site\/wp-content\/uploads\/2021\/05\/plus-value-france-casdastre.jpg\",\"datePublished\":\"2021-05-10T05:45:00+00:00\",\"dateModified\":\"2024-11-25T09:19:28+00:00\",\"author\":{\"@id\":\"https:\/\/france-cadastre.fr\/site\/#\/schema\/person\/143233e0b94cc8ee6727937ff598c57c\"},\"breadcrumb\":{\"@id\":\"https:\/\/france-cadastre.fr\/site\/plus-value-terrain-2021\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/france-cadastre.fr\/site\/plus-value-terrain-2021\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/france-cadastre.fr\/site\/plus-value-terrain-2021\/#primaryimage\",\"url\":\"https:\/\/france-cadastre.fr\/site\/wp-content\/uploads\/2021\/05\/plus-value-france-casdastre.jpg\",\"contentUrl\":\"https:\/\/france-cadastre.fr\/site\/wp-content\/uploads\/2021\/05\/plus-value-france-casdastre.jpg\",\"width\":600,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/france-cadastre.fr\/site\/plus-value-terrain-2021\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/france-cadastre.fr\/site\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PLUS-VALUE TERRAIN 2021\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/france-cadastre.fr\/site\/#website\",\"url\":\"https:\/\/france-cadastre.fr\/site\/\",\"name\":\"France Cadastre\",\"description\":\"Le cadastre fran\u00e7ais accessible \u00e0 tous !\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/france-cadastre.fr\/site\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/france-cadastre.fr\/site\/#\/schema\/person\/143233e0b94cc8ee6727937ff598c57c\",\"name\":\"valentin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/france-cadastre.fr\/site\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/bbf36e20b63d7d02209b58ef5decd017f817d7eb18dedb87e1c6ef13c562a83b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/bbf36e20b63d7d02209b58ef5decd017f817d7eb18dedb87e1c6ef13c562a83b?s=96&d=mm&r=g\",\"caption\":\"valentin\"},\"url\":\"https:\/\/france-cadastre.fr\/site\/author\/valentin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PLUS-VALUE TERRAIN 2021 - France Cadastre","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/france-cadastre.fr\/site\/plus-value-terrain-2021\/","og_locale":"fr_FR","og_type":"article","og_title":"PLUS-VALUE TERRAIN 2021 - France Cadastre","og_description":"En ce qui concerne la taxation des plus-values \u200b\u200br\u00e9alis\u00e9es lors de la vente du terrain, les contribuables se trouveront confront\u00e9s \u00e0 plusieurs situations, selon que le terrain en question est h\u00e9rit\u00e9, qu&rsquo;il s&rsquo;agisse d&rsquo;une exploitation agricole, ou qu&rsquo;il soit possible&hellip;","og_url":"https:\/\/france-cadastre.fr\/site\/plus-value-terrain-2021\/","og_site_name":"France Cadastre","article_published_time":"2021-05-10T05:45:00+00:00","article_modified_time":"2024-11-25T09:19:28+00:00","og_image":[{"width":600,"height":400,"url":"https:\/\/france-cadastre.fr\/site\/wp-content\/uploads\/2021\/05\/plus-value-france-casdastre.jpg","type":"image\/jpeg"}],"author":"valentin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"valentin","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/france-cadastre.fr\/site\/plus-value-terrain-2021\/","url":"https:\/\/france-cadastre.fr\/site\/plus-value-terrain-2021\/","name":"PLUS-VALUE TERRAIN 2021 - France Cadastre","isPartOf":{"@id":"https:\/\/france-cadastre.fr\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/france-cadastre.fr\/site\/plus-value-terrain-2021\/#primaryimage"},"image":{"@id":"https:\/\/france-cadastre.fr\/site\/plus-value-terrain-2021\/#primaryimage"},"thumbnailUrl":"https:\/\/france-cadastre.fr\/site\/wp-content\/uploads\/2021\/05\/plus-value-france-casdastre.jpg","datePublished":"2021-05-10T05:45:00+00:00","dateModified":"2024-11-25T09:19:28+00:00","author":{"@id":"https:\/\/france-cadastre.fr\/site\/#\/schema\/person\/143233e0b94cc8ee6727937ff598c57c"},"breadcrumb":{"@id":"https:\/\/france-cadastre.fr\/site\/plus-value-terrain-2021\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/france-cadastre.fr\/site\/plus-value-terrain-2021\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/france-cadastre.fr\/site\/plus-value-terrain-2021\/#primaryimage","url":"https:\/\/france-cadastre.fr\/site\/wp-content\/uploads\/2021\/05\/plus-value-france-casdastre.jpg","contentUrl":"https:\/\/france-cadastre.fr\/site\/wp-content\/uploads\/2021\/05\/plus-value-france-casdastre.jpg","width":600,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/france-cadastre.fr\/site\/plus-value-terrain-2021\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/france-cadastre.fr\/site\/"},{"@type":"ListItem","position":2,"name":"PLUS-VALUE TERRAIN 2021"}]},{"@type":"WebSite","@id":"https:\/\/france-cadastre.fr\/site\/#website","url":"https:\/\/france-cadastre.fr\/site\/","name":"France Cadastre","description":"Le cadastre fran\u00e7ais accessible \u00e0 tous !","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/france-cadastre.fr\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/france-cadastre.fr\/site\/#\/schema\/person\/143233e0b94cc8ee6727937ff598c57c","name":"valentin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/france-cadastre.fr\/site\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/bbf36e20b63d7d02209b58ef5decd017f817d7eb18dedb87e1c6ef13c562a83b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bbf36e20b63d7d02209b58ef5decd017f817d7eb18dedb87e1c6ef13c562a83b?s=96&d=mm&r=g","caption":"valentin"},"url":"https:\/\/france-cadastre.fr\/site\/author\/valentin\/"}]}},"_links":{"self":[{"href":"https:\/\/france-cadastre.fr\/site\/wp-json\/wp\/v2\/posts\/307","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/france-cadastre.fr\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/france-cadastre.fr\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/france-cadastre.fr\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/france-cadastre.fr\/site\/wp-json\/wp\/v2\/comments?post=307"}],"version-history":[{"count":1,"href":"https:\/\/france-cadastre.fr\/site\/wp-json\/wp\/v2\/posts\/307\/revisions"}],"predecessor-version":[{"id":309,"href":"https:\/\/france-cadastre.fr\/site\/wp-json\/wp\/v2\/posts\/307\/revisions\/309"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/france-cadastre.fr\/site\/wp-json\/wp\/v2\/media\/308"}],"wp:attachment":[{"href":"https:\/\/france-cadastre.fr\/site\/wp-json\/wp\/v2\/media?parent=307"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/france-cadastre.fr\/site\/wp-json\/wp\/v2\/categories?post=307"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/france-cadastre.fr\/site\/wp-json\/wp\/v2\/tags?post=307"},{"taxonomy":"post_series","embeddable":true,"href":"https:\/\/france-cadastre.fr\/site\/wp-json\/wp\/v2\/post_series?post=307"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}